{"id":7328,"count":16,"description":"","link":"https:\/\/oman.generaltec.com\/ar\/shop\/brand\/generaltec\/","name":"Generaltec","slug":"generaltec","taxonomy":"brand","parent":0,"meta":{"thumbnail_id":["0"]},"image":{"id":["0"],"src":false,"alt":false,"title":"","caption":"","description":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Generaltec Archives - Generaltec<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Generaltec Archives - Generaltec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oman.generaltec.com\/shop\/brand\/generaltec\/\" \/>\n<meta property=\"og:site_name\" content=\"Generaltec\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/shop\\\/brand\\\/generaltec\\\/\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/shop\\\/brand\\\/generaltec\\\/\",\"name\":\"Generaltec Archives - Generaltec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/shop\\\/brand\\\/generaltec\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/shop\\\/brand\\\/generaltec\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oman.generaltec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Generaltec\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#website\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/\",\"name\":\"Generaltec\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oman.generaltec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#organization\",\"name\":\"Generaltec\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/015-Google-copy.png\",\"contentUrl\":\"https:\\\/\\\/oman.generaltec.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/015-Google-copy.png\",\"width\":512,\"height\":307,\"caption\":\"Generaltec \"},\"image\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Generaltec Archives - Generaltec","robots":{"index":"noindex","follow":"follow"},"og_locale":"ar_AR","og_type":"article","og_title":"Generaltec Archives - Generaltec","og_url":"https:\/\/oman.generaltec.com\/shop\/brand\/generaltec\/","og_site_name":"Generaltec","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oman.generaltec.com\/shop\/brand\/generaltec\/","url":"https:\/\/oman.generaltec.com\/shop\/brand\/generaltec\/","name":"Generaltec Archives - Generaltec","isPartOf":{"@id":"https:\/\/oman.generaltec.com\/#website"},"breadcrumb":{"@id":"https:\/\/oman.generaltec.com\/shop\/brand\/generaltec\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/oman.generaltec.com\/shop\/brand\/generaltec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oman.generaltec.com\/"},{"@type":"ListItem","position":2,"name":"Generaltec"}]},{"@type":"WebSite","@id":"https:\/\/oman.generaltec.com\/#website","url":"https:\/\/oman.generaltec.com\/","name":"Generaltec","description":"","publisher":{"@id":"https:\/\/oman.generaltec.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oman.generaltec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/oman.generaltec.com\/#organization","name":"Generaltec","url":"https:\/\/oman.generaltec.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/oman.generaltec.com\/#\/schema\/logo\/image\/","url":"https:\/\/oman.generaltec.com\/wp-content\/uploads\/2025\/02\/015-Google-copy.png","contentUrl":"https:\/\/oman.generaltec.com\/wp-content\/uploads\/2025\/02\/015-Google-copy.png","width":512,"height":307,"caption":"Generaltec "},"image":{"@id":"https:\/\/oman.generaltec.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/etheme_brands\/7328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/etheme_brands"}],"about":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/taxonomies\/brand"}],"wp:post_type":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/product?etheme_brands=7328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}