{"id":5576,"count":0,"description":"","link":"https:\/\/oman.generaltec.com\/ar\/tag\/%d9%85%d9%88%d8%b2%d8%b9-%d9%85%d9%8a%d8%a7%d9%87-%d9%84%d9%84%d9%85%d9%86%d8%b2%d9%84\/","name":"\u0645\u0648\u0632\u0639 \u0645\u064a\u0627\u0647 \u0644\u0644\u0645\u0646\u0632\u0644","slug":"%d9%85%d9%88%d8%b2%d8%b9-%d9%85%d9%8a%d8%a7%d9%87-%d9%84%d9%84%d9%85%d9%86%d8%b2%d9%84","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0645\u0648\u0632\u0639 \u0645\u064a\u0627\u0647 \u0644\u0644\u0645\u0646\u0632\u0644 Archives - Generaltec<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0645\u0648\u0632\u0639 \u0645\u064a\u0627\u0647 \u0644\u0644\u0645\u0646\u0632\u0644 Archives - Generaltec\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oman.generaltec.com\/tag\/water-dispenser-for-home\/\" \/>\n<meta property=\"og:site_name\" content=\"Generaltec\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/tag\\\/water-dispenser-for-home\\\/\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/tag\\\/water-dispenser-for-home\\\/\",\"name\":\"\u0645\u0648\u0632\u0639 \u0645\u064a\u0627\u0647 \u0644\u0644\u0645\u0646\u0632\u0644 Archives - Generaltec\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/tag\\\/water-dispenser-for-home\\\/#breadcrumb\"},\"inLanguage\":\"ar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/tag\\\/water-dispenser-for-home\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/oman.generaltec.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Water Dispenser for Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#website\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/\",\"name\":\"Generaltec\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oman.generaltec.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#organization\",\"name\":\"Generaltec\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oman.generaltec.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/015-Google-copy.png\",\"contentUrl\":\"https:\\\/\\\/oman.generaltec.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/015-Google-copy.png\",\"width\":512,\"height\":307,\"caption\":\"Generaltec \"},\"image\":{\"@id\":\"https:\\\/\\\/oman.generaltec.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0645\u0648\u0632\u0639 \u0645\u064a\u0627\u0647 \u0644\u0644\u0645\u0646\u0632\u0644 Archives - Generaltec","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"ar_AR","og_type":"article","og_title":"\u0645\u0648\u0632\u0639 \u0645\u064a\u0627\u0647 \u0644\u0644\u0645\u0646\u0632\u0644 Archives - Generaltec","og_url":"https:\/\/oman.generaltec.com\/tag\/water-dispenser-for-home\/","og_site_name":"Generaltec","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oman.generaltec.com\/tag\/water-dispenser-for-home\/","url":"https:\/\/oman.generaltec.com\/tag\/water-dispenser-for-home\/","name":"\u0645\u0648\u0632\u0639 \u0645\u064a\u0627\u0647 \u0644\u0644\u0645\u0646\u0632\u0644 Archives - Generaltec","isPartOf":{"@id":"https:\/\/oman.generaltec.com\/#website"},"breadcrumb":{"@id":"https:\/\/oman.generaltec.com\/tag\/water-dispenser-for-home\/#breadcrumb"},"inLanguage":"ar"},{"@type":"BreadcrumbList","@id":"https:\/\/oman.generaltec.com\/tag\/water-dispenser-for-home\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/oman.generaltec.com\/"},{"@type":"ListItem","position":2,"name":"Water Dispenser for Home"}]},{"@type":"WebSite","@id":"https:\/\/oman.generaltec.com\/#website","url":"https:\/\/oman.generaltec.com\/","name":"Generaltec","description":"","publisher":{"@id":"https:\/\/oman.generaltec.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oman.generaltec.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/oman.generaltec.com\/#organization","name":"Generaltec","url":"https:\/\/oman.generaltec.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/oman.generaltec.com\/#\/schema\/logo\/image\/","url":"https:\/\/oman.generaltec.com\/wp-content\/uploads\/2025\/02\/015-Google-copy.png","contentUrl":"https:\/\/oman.generaltec.com\/wp-content\/uploads\/2025\/02\/015-Google-copy.png","width":512,"height":307,"caption":"Generaltec "},"image":{"@id":"https:\/\/oman.generaltec.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/tags\/5576","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/oman.generaltec.com\/ar\/wp-json\/wp\/v2\/posts?tags=5576"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}